{"id":38956,"date":"2025-09-03T14:08:09","date_gmt":"2025-09-03T12:08:09","guid":{"rendered":"https:\/\/srfb.be\/?p=38956"},"modified":"2025-09-03T14:17:28","modified_gmt":"2025-09-03T12:17:28","slug":"comment-adapter-les-forets-aux-changements-climatiques","status":"publish","type":"post","link":"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/","title":{"rendered":"Wie k\u00f6nnen die W\u00e4lder an den Klimawandel angepasst werden?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Der Klimawandel wirkt sich auf viele Waldarten und die Funktionsweise der Wald\u00f6kosysteme selbst aus. Die F\u00f6rster fragen sich, wie sie ihre W\u00e4lder am besten anpassen k\u00f6nnen, um sie widerstandsf\u00e4higer zu machen. Dies ist nicht einfach, da es keine Patentrezepte gibt und die zu ber\u00fccksichtigenden Faktoren aus verschiedenen Bereichen stammen: Pflanzenphysiologie, Bodenschutz, forstwirtschaftliche Strategie, Einf\u00fchrung neuer Baumarten und Herk\u00fcnfte...<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Artikel erl\u00e4utert einige grundlegende Punkte zu diesen Themen, die der Forstwirt nicht ignorieren darf.<\/p>\n\n\n\n<div class=\"wp-block-group has-grey-color-background-color has-background is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Zusammenfassung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt kein Patentrezept, um W\u00e4lder widerstandsf\u00e4hig zu machen. Um dieses Ziel zu erreichen, muss die Waldbewirtschaftung eine Vielzahl von Faktoren ber\u00fccksichtigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Verst\u00e4ndnis der Anpassungsstrategien von Baumarten an Trockenheit geh\u00f6rt zu den Grundlagen, um die richtige Baumartenwahl f\u00fcr den jeweiligen Standort zu treffen. Was sind die Vermeidungsstrategie und die Toleranzstrategie durch Verz\u00f6gerung der Austrocknung? Was sind die St\u00e4rken und Grenzen dieser Strategien? Welche Baumarten sind betroffen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Artikel beantwortet diese Fragen zur Pflanzenphysiologie, bevor er auf weitere unverzichtbare und reflektierte Fragen zur Bodenerhaltung, zu forstwirtschaftlichen Techniken und zur Einf\u00fchrung von Baumarten und Herk\u00fcnften eingeht.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-a6708d498a95ee884b033030e044aca7\">1. Pflanzenphysiologie<sup>*<\/sup><\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-b11294c239e9893d9a58872902a29963\">Pr\u00e4ambel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wasser (Rohsaft<sup>1<\/sup>) steigt in der Welle durch ein Spannungsph\u00e4nomen, das direkt mit dem Verdunstungsbedarf der Luft zusammenh\u00e4ngt. Dieser Bedarf<br>wird durch die Evapotranspiration befriedigt<sup>2<\/sup> auf den Bl\u00e4ttern. So gelangt unter dem Einfluss von W\u00e4rme (Sonnenenergie) das fl\u00fcssige Wasser in den Bl\u00e4ttern durch die<br>in der Umgebungsluft in gasf\u00f6rmigem Zustand. Dies f\u00fchrt zu einem Wassermangel in den Bl\u00e4ttern, der den Baum unter Spannung setzt und den Saft aufsteigen l\u00e4sst. Durch den \u00abDominoeffekt\u00bb f\u00fchrt der aufsteigende Saft zu einer Spannung in den Wurzeln, die diese durch die Aufnahme von Wasser aus dem Boden (Rohsaft) ausgleichen. <strong>Die Evapotranspiration ist also die treibende Kraft hinter dem Wasserkreislauf im Baum.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Bodenwasser knapp wird und eine Edaphische Trockenheit einsetzt, wird die Spannung st\u00e4rker, und zwar umso mehr, wenn der Verdunstungsbedarf der Luft hoch ist (trockene Luft). Dies kann zu Br\u00fcchen in den Wassers\u00e4ulen der Gef\u00e4\u00dfe f\u00fchren, die den aufsteigenden Saft leiten. Dieses Ph\u00e4nomen des Aufbrechens wird als <strong>Kavitation<\/strong>. Dies f\u00fchrt dazu, dass sich Luftblasen in der Wassers\u00e4ule bilden.\u2019<strong>Luftembolie<\/strong>. Diese behindert den Wasserfluss oder macht ihn sogar unm\u00f6glich.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"767\" height=\"719\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/photosynthese.png\" alt=\"\" class=\"wp-image-38959 size-full\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/photosynthese.png 767w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/photosynthese-300x281.png 300w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/photosynthese-13x12.png 13w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/photosynthese-600x562.png 600w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Die Photosynthese<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Chloroplasten fangen Lichtenergie ein<\/li>\n\n\n\n<li>Wasser dringt in das Blatt ein<\/li>\n\n\n\n<li>Das CO<sub>2<\/sub> dringt in das Blatt ein<\/li>\n\n\n\n<li>Der Zucker verl\u00e4sst das Blatt<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-left:var(--wp--preset--spacing--50)\">A. Schiff<br>B. Stoma<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"margin-bottom:var(--wp--preset--spacing--60)\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-photosynthese-769x1024.png.webp\" alt=\"\" class=\"wp-image-38961 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Die von den Pflanzen synthetisierten Zucker dienen der Atmung, dem Wachstum und der Verteidigung (siehe Punkt 4). Ein Teil dieser Zucker wird in Form von St\u00e4rke gespeichert, vor allem am Wurzelhals und an den gro\u00dfen Dachst\u00fchlen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-grey-color-border-color is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"border-width:3px;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Hinweis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wurzelabsorption ist durch Mykorrhiza m\u00f6glich<sup>3<\/sup>, In der Regel sind es die Pilze, die das Wasser aus dem Boden pumpen und es dann an die Wurzeln abgeben. Im Gegenzug gibt der Baum den Pilzen einen Teil des Zuckers, den er durch Photosynthese synthetisiert hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Teil des Blattwassers wird f\u00fcr die Photosynthese verwendet, eine photochemische Reaktion, bei der Wasser (Rohsaft) und atmosph\u00e4risches Kohlendioxid (das von den Bl\u00e4ttern aufgenommen wird) in Glukose (Zucker) umgewandelt werden und Sauerstoff entsteht. Diese komplexe Reaktion findet in den Bl\u00e4ttern statt und ist nur in Gegenwart von Chlorophyll m\u00f6glich. Seine vereinfachte Formel lautet 6 CO<sub>2<\/sub> + 6 H<sub>2<\/sub>O <span class=\"wp-rich-text-font-awesome-icon wp-font-awesome-icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\" data-icon=\"arrow-right-long\" class=\"svg-inline--fa fa-arrow-right-long\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M502.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-128-128c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L402.7 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l370.7 0-73.4 73.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l128-128z\"><\/path><\/svg><\/span> C<sub>6<\/sub>H<sub>12<\/sub>O<sub>6<\/sub> + 6 O<sub>2<\/sub>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die produzierte Glukose wird von der Pflanze f\u00fcr ihren Stoffwechsel verwendet.<sup>4<\/sup> oder in Form von St\u00e4rke gespeichert (Reserven).<\/p>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Wasser und gel\u00f6ste Mineralsalze, die im Boden vorhanden sind.<\/li>\n\n\n\n<li>Es ist korrekter, von Evapotranspiration statt von Transpiration zu sprechen, da dieser Begriff eher auf die Tierwelt zutrifft.<\/li>\n\n\n\n<li>Symbiotische Verbindung zwischen einem Pilz und den Wurzeln einer h\u00f6heren Pflanze. Man spricht von Mykorrhiza-Symbiose (Symbiose ist eine wechselseitig vorteilhafte Verbindung zwischen mehreren Organismen).<\/li>\n\n\n\n<li>Der Stoffwechsel ist die Gesamtheit der chemischen Reaktionen, die in jeder Zelle eines Lebewesens ablaufen und es insbesondere in die Lage versetzen, sich am Leben zu erhalten, sich fortzupflanzen, zu entwickeln und auf Reize aus seiner Umwelt zu reagieren. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/M%C3%A9tabolisme\" target=\"_blank\" rel=\"noreferrer noopener\">Quelle: Wikipedia<\/a><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-left:var(--wp--preset--spacing--50)\">* Die Pflanzenphysiologie befasst sich mit der Funktionsweise von Pflanzenorganen und -gewebe und versucht, die Art der Mechanismen zu kl\u00e4ren, durch die die Organe ihre Funktionen erf\u00fcllen und die Pflanze sich in ihrer Umwelt entwickelt. Sie umfasst insbesondere das Studium der Wasserverh\u00e4ltnisse und der Photosynthese. Quelle: <a href=\"https:\/\/biologievegetale.be\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/biologievegetale.be<\/a><\/p>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-0343475d0c5c0c71f532a071b57fed44\">1.1 Strategien der Baumarten im Umgang mit Trockenheit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unter den Waldbaumarten gibt es drei Strategien zur Anpassung an die Trockenheit.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-83daf489fd56795a6ed7b584976f1138\">1.1.1. Die Vermeidungsstrategie<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Vermeidungsstrategie st\u00fctzt sich insbesondere auf :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die <strong>Ph\u00e4nologie<sup>1<\/sup> asynchron<\/strong> auf die Trockenperiode, die bei einigen Baumarten vorkommt. Im Mittelmeerraum wird z. B. die Steineiche im Fr\u00fchjahr und im Herbst wachsen. Im Sommer, von Juni bis September, stellt sie ihre Vegetation vollst\u00e4ndig ein ;<\/li>\n\n\n\n<li>die <strong>fr\u00fches Schlie\u00dfen der Spalt\u00f6ffnungen<sup>2<\/sup><\/strong>, was bei Wassermangel das Blattwasserpotenzial aufrechterh\u00e4lt. Anders ausgedr\u00fcckt, die Schlie\u00dfung der Spalt\u00f6ffnungen stoppt die Evapotranspiration und schlie\u00dft das Wasser im Inneren der Pflanze ein.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Evitationsstrategie findet sich nicht bei Laubb\u00e4umen der gem\u00e4\u00dfigten Zone, deren stomat\u00e4re Regulation begrenzt ist. Bei edaphischer Trockenheit wird sich die Stomata\u00f6ffnung teilweise schlie\u00dfen, mit einem variablen \u00d6ffnungsgrad je nach Art. Zum Beispiel ist die amerikanische Roteiche bei diesem \u00abkleinen Spiel\u00bb leistungsf\u00e4higer als unsere einheimischen Eichen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-69902f180503812a1c19a9dea86311e1\">1.1.2. Die Strategie der Toleranz durch Verz\u00f6gerung der Austrocknung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Strategie ist inh\u00e4rent in den <strong>Essenzen, die eine tiefe Wurzelbildung erm\u00f6glichen<\/strong>. Sie sind daher in der Lage, Wasser aus der Tiefe zu sch\u00f6pfen und die Photosynthese fortzusetzen, solange Wasser verf\u00fcgbar ist, selbst bei \u00abOberfl\u00e4chen-D\u00fcrre\u00bb und Hitzewellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Strategie st\u00fctzt sich auch auf eine <strong>Morphologische Anpassung der Leitgef\u00e4\u00dfe<\/strong> (dicker) die ihre Kavitationsbest\u00e4ndigkeit erh\u00f6ht und somit das Risiko von Embolien verringert.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-60c58f2bfcb052227f0927312d30c975\">1.1.3. Die Strategie der D\u00fcrreresistenz<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Strategie betrifft Pflanzen, die Wasser in ihren Geweben speichern k\u00f6nnen. Sie betrifft nicht die gem\u00e4\u00dfigte Zone. Einige Arten kombinieren mehrere Strategien, wie zum Beispiel die Steineiche, die die Vermeidung und die Toleranz durch verz\u00f6gerte Austrocknung kombiniert. Dies gilt auch f\u00fcr einige Cupressus-Arten und generell f\u00fcr immergr\u00fcne Laubb\u00e4ume. Einheimische Eichen und die Atlas-Zeder nutzen die Strategie der Toleranz durch verz\u00f6gerte Austrocknung (tiefe Verwurzelung). Pinien nutzen die Strategie der Vermeidung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ob die gew\u00e4hlte Strategie einzeln oder kombiniert ist, ihre Wirksamkeit wird von Baumart zu Baumart variieren. So wird die Traubeneiche (sessile Eiche) widerstandsf\u00e4higer gegen Trockenheit sein als die Stieleiche (pedunculate Eiche), die empfindlicher auf Wassermangel reagiert und ihr Optimum nur auf st\u00e4ndig gut versorgten Standorten findet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist absolut grundlegend, diese beiden Strategien zur Anpassung an Trockenheit zu verstehen, um die richtige Wahl der Baumarten je nach Standort zu treffen. Zum Beispiel besitzt die Atlas-Zeder eine sehr gute Trockenheitsresistenz, aber ihre Wurzelbildung ist sehr empfindlich gegen\u00fcber Bodenverdichtung und Anaerobiose. Doch gerade ihre Wurzelbildung (pfahlwurzelartig und kr\u00e4ftig) verleiht ihr diese Resistenz. Daher ist ihre Pflanzung auf B\u00f6den mit verdichtetem, staun\u00e4ssetr\u00e4chtigem oder flachgr\u00fcndigem Horizont ein unbedingt zu vermeidender forstlicher Fehler. Unter solchen Umst\u00e4nden entwickelt sich die Wurzelbildung der Atlas-Zeder nicht, was ihre Strategie zur Anpassung an Trockenheit zunichtemacht. Beachten Sie, dass die Wurzelbildung der Atlas-Zeder auch durch abrupte Bodentextur\u00e4nderungen stark behindert wird.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Die Ph\u00e4nologie ist die Untersuchung des Auftretens von periodischen Ereignissen in der lebenden Welt, bestimmt durch die jahreszeitlichen Klimaschwankungen. Quelle: <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ph%C3%A9nologie\" target=\"_blank\" rel=\"noreferrer noopener\">Wikipedia<\/a><\/li>\n\n\n\n<li>Ensemble aus zwei nierenf\u00f6rmigen Zellen (Schlie\u00dfzellen oder Garde-Zellen), reich an Chlorophyll, mit einer kleinen \u00d6ffnung (Ostiole) dazwischen, durch die die Gasaustauschvorg\u00e4nge der Pflanze stattfinden (Atmung, Evapotranspiration, Photosynthese). Quelle: <a href=\"https:\/\/www.larousse.fr\/dictionnaires\/francais\/stomate\/74771\" target=\"_blank\" rel=\"noreferrer noopener\">Dictionnaire Larousse<\/a>. Anm.: Die Spalt\u00f6ffnungen befinden sich im Allgemeinen auf der Blattunterseite. Bei einigen Pflanzenarten k\u00f6nnen sie sich auch auf der Blattoberseite und an den St\u00e4ngeln befinden.<\/li>\n<\/ol>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-d958bbec6f66d75e168da898d9222557\">1.2. Grenzen von Anpassungsstrategien<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Schlie\u00dfen der Spalt\u00f6ffnungen im Zusammenhang mit <strong>Ausweichstrategie<\/strong> verursacht einen R\u00fcckgang der photosynthetischen Aktivit\u00e4t. Tats\u00e4chlich werden der Gasaustausch zwischen Blatt und Atmosph\u00e4re blockiert, der Baum spart Wasser, aber die CO2-Aufnahme<sub>2<\/sub> notwendige f\u00fcr die Photosynthese stoppt. Der Baum wird dann seine St\u00e4rkereserven nutzen, um seinen Stoffwechsel aufrechtzuerhalten. Nach einer vor\u00fcbergehenden D\u00fcrre wird der Baum schnell zu seinem normalen Funktionieren zur\u00fcckkehren, aber <strong>anhaltende und wiederkehrende D\u00fcrren<\/strong> die Kraft des Baumes allm\u00e4hlich schw\u00e4chen (nicht mehr gen\u00fcgend St\u00e4rke auf Lager, um im Fr\u00fchjahr gen\u00fcgend neue Bl\u00e4tter zu bilden), was schlie\u00dflich dazu f\u00fchren wird, dass <strong>verhungern<\/strong> (nicht mehr genug Photosynthese und keine Reserven mehr).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der <strong>Trocknungstoleranzstrategie durch Verz\u00f6gerung<\/strong>, wird der Baum seine photosynthetische T\u00e4tigkeit fortsetzen, solange er im Boden Wasser findet. Sobald es an Wasser mangelt, kommt es zur Embolie und der Baum (oder Ast) stirbt schlie\u00dflich <strong>verdursten<\/strong>. F\u00fcr Essenzen, die diese Strategie verfolgen, sind dies die <strong>intensive und anhaltende D\u00fcrren<\/strong> die ihnen schaden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-6f01893a3e063f15777e8a1968e18606\">1.3. Vorzeitiger Blattfall<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine weitere m\u00f6gliche Reaktion auf Trockenheit ist der vorzeitige Laubabwurf, um den Wasserverlust zu begrenzen (wie beispielsweise bei der Birke). Diese \u00dcberlebensstrategie stellt ein gro\u00dfes Problem f\u00fcr die Reserven des Baumes dar, da sie das Photosynthese-Potenzial verringert und zudem zu einem Verlust an N\u00e4hrstoffen f\u00fchrt. Im Herbst geht der Laubabwurf mit einer R\u00fcckgewinnung von etwa 50% der darin enthaltenen N\u00e4hrstoffe einher, die in den Zweigen f\u00fcr den Austrieb im folgenden Fr\u00fchjahr gespeichert werden. Wenn der Baum seine Bl\u00e4tter w\u00e4hrend der Vegetationsperiode \u00abloswerden\u00bb muss, findet keine R\u00fcckgewinnung von N\u00e4hrstoffen statt; die Bl\u00e4tter fallen gr\u00fcn zu Boden. Dies schw\u00e4cht den Baum erheblich.<\/p>\n\n\n\n<div class=\"wp-block-group has-vert-claire-color-background-color has-background is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Anf\u00e4lligkeit von Baumarten f\u00fcr Verstopfung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Anf\u00e4lligkeit f\u00fcr Embolien kann grafisch dargestellt werden, indem der Zustand des Saftes in den Xylemgef\u00e4\u00dfen in Beziehung gesetzt wird.<sup>1<\/sup> (Wasserpotenzial in MPa) und den Emboliegrad (PLC %).<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"685\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-article.png\" alt=\"\" class=\"wp-image-38965 size-full\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-article.png 780w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-article-300x263.png 300w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-article-14x12.png 14w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-article-600x527.png 600w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Anf\u00e4lligkeitskurve einer Rotbuche<\/h4>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:italic;font-weight:300\">Quelle: Wortemann R., Variabilit\u00e4t der Kavitationsanf\u00e4lligkeit bei Rotbuche. Kolloquium Xylem, INRA Nancy, 23 S.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ein h\u00e4ufig verwendeter Wert zum Vergleich von Arten ist der P50-Wert, d.\u202fh. das Wasserpotenzial, bei dem ein Leitf\u00e4higkeitsabfall von 50 % gemessen wird (50-%-Embolie). Der P50-Wert sollte nicht als absoluter Ma\u00dfstab betrachtet werden, da es sich um standardisierte Labordaten handelt. In der Natur spielen viele weitere Parameter eine Rolle, daher ist der P50-Wert zwar ein Anhaltspunkt, spiegelt aber nicht unbedingt die tats\u00e4chlichen Gegebenheiten vor Ort wider.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphique-vulnerabilite-1024x806.png.webp\" alt=\"\" class=\"wp-image-38966\" style=\"object-fit:cover\"\/><figcaption class=\"wp-element-caption\"><em>Quelle : Nach Cochard H. et al., 2016. Embolie und Trockenheitsanf\u00e4lligkeit von B\u00e4umen, INRA Clermont-Ferrand.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Zum Beispiel ist der P50 der Traubeneiche (Quercus petraea) etwas h\u00f6her als der der Fichte (Picea abies) (siehe Grafik). W\u00fcrde man sich nur auf diese Angabe verlassen, k\u00f6nnte man daraus schlie\u00dfen, dass die Fichte trockenerresistenter ist als die Traubeneiche! Die Dinge sind viel komplizierter, eine Traubeneiche auf tiefem Boden mit guter nutzbarer Feldkapazit\u00e4t (siehe Kasten S. 21) wird keine Probleme mit Kavitation haben, was bei der Fichte (flaches Wurzelsystem) bei \u00abOberfl\u00e4chenrockenheit\u00bb nicht unbedingt der Fall sein wird.\u00bb<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vert-fonce-color-color has-alpha-channel-opacity has-vert-fonce-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Holzteil, in dem der Rohsaft zirkuliert.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-43bb3bddf4437246e3c30f559be1360e\">1.4. Abwehr und Wasserstress<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Synthese von Abwehrmolek\u00fclen von B\u00e4umen (Polyphenole, Alkaloide etc.) erfordert viel Energie (Zucker) (siehe Schema in der Einleitung). Bei Wasserstress, der zu einem R\u00fcckgang der Photosynthese und damit zu einem Abbau der Reserven f\u00fchrt, wird der Baum vorrangig das abbauen, was am energieaufw\u00e4ndigsten ist, d.h. die Synthese von Abwehrmolek\u00fclen, um sein metabolisches \u00dcberleben (Atmung und Wachstum) zu sichern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Prinzip ist offensichtlich von Esche zu Esche zu nuancieren. Fichte ist ein typisches Beispiel f\u00fcr die negativen Auswirkungen von Wasserstress auf die Abwehrkr\u00e4fte der Esche. Bei Wasserstress stoppt die Fichte die Synthese ihrer Abwehrmolek\u00fcle. Die Folge, die den Forstleuten leider wohlbekannt ist, sind Massenangriffe von Ips typographus (Fichtenborkenk\u00e4fer) in Reinbest\u00e4nden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-009aa3a7dda53e8df88ec621373e22db\">Indikatoren f\u00fcr den Baumr\u00fcckgang<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">B\u00e4ume, die unter einer oder mehreren D\u00fcrren gelitten haben, weisen folgende Symptome auf:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>des mortalit\u00e9s de branches ou de l\u2019arbre, en fonction du degr\u00e9 de cavitation au sein des individus ;<\/li>\n\n\n\n<li>lichte Baumkronen zum Zeitpunkt des Austreibens im Jahr nach der Belastung;<\/li>\n\n\n\n<li>eine Verringerung des Wachstums;<\/li>\n\n\n\n<li>eine Empfindlichkeit gegen\u00fcber Krankheitserregern.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-91e81e7b8836717520c5e6820a2c16d9\">1.6. Wachstum und Anpassungsstrategie<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist logisch, dass D\u00fcrren das Baumwachstum je nach Anpassungsstrategie unterschiedlich beeinflussen. Die Vermeidungsstrategie wird sich negativ auf das Wachstum auswirken (geringere Photosynthese). Ein Stieleiche kann seine Produktivit\u00e4t w\u00e4hrend einer D\u00fcrre hingegen gut aufrechterhalten, wenn ihre tiefreichende Wurzelstruktur ausreichend entwickelt ist und dort verf\u00fcgbares Wasser findet (keine Abnahme der Photosynthese).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus wird eine Installation an den hydrologisch besten Standorten keinen so positiven Einfluss auf das Wachstum bei Arten haben, die die Strategie der D\u00fcrretoleranz durch Verz\u00f6gerung anwenden, wie bei Arten, die sich auf die Vermeidungsstrategie verlassen. Erstere sind genetisch \u00abprogrammiert\u00bb, ihre Gef\u00e4\u00dfe zu \u00abpanzern\u00bb, um Kavitationen zu widerstehen, was viel Energie und Kohlenstoff kostet. Sie werden sich immer in erster Linie auf diesen Aspekt \u00abkonzentrieren\u00bb. Letztere werden dagegen, befreit von hydrologischen Einschr\u00e4nkungen, f\u00fcr ihr Wachstum Photosynthese betreiben. Mit anderen Worten, die Allokation von Zuckern aus der Photosynthese hat je nach Anpassungsstrategie der Art unterschiedliche Priorit\u00e4ten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt auch deutliche Unterschiede im Wachstumsgewinn je nach Standort f\u00fcr Arten, die dieselbe Strategie verfolgen. Beispielsweise hat die Steineiche eine geringere potenzielle Wachstumsspanne als die Traubeneiche, da die Steineiche eine st\u00e4rkere Strategie der Austrocknungstoleranz durch Verz\u00f6gerung aufweist. Mit anderen Worten, die Steineiche wird auf den besten Standorten nicht so viel (oder gar nicht) im Wachstum zulegen wie die Traubeneiche, wird aber auf den anspruchsvollen Standorten der Trockenheit besser widerstehen.<\/p>\n\n\n\n<div class=\"wp-block-columns has-vert-claire-color-background-color has-background has-link-color wp-elements-2bfe4c7f19085c056c1d0675def96e80 is-layout-flex wp-container-core-columns-is-layout-6b285452 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h2 class=\"wp-block-heading\">Speicherbare nutzbare Feldkapazit\u00e4t<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die nutzbare Wasserspeicherung ist die Menge an Wasser, die Pflanzen in der von den Wurzeln durchdrungenen Bodenschicht zur Verf\u00fcgung steht. Sie wird in Millimetern angegeben. Sie h\u00e4ngt von der Art der Bewurzelung des Baumes und den Bodeneigenschaften ab. Sie ist direkt proportional zur nutzbaren Bodentiefe. Die Bodenart (Lehm, Schluff, Sand) ist grundlegend. Lehmige B\u00f6den haben eine h\u00f6here nutzbare Wasserspeicherung als schluffige und erst recht als sandige B\u00f6den. Die nutzbare Wasserspeicherung wird auch durch den Anteil an groben Bestandteilen (Kies &gt; 2 mm, Steine) beeinflusst. Je h\u00f6her dieser Anteil ist, desto geringer ist die nutzbare Wasserspeicherung.<br>Im Durchschnitt verdunsten und transpirieren (evapotranspirieren) 30 bis 40 Tonnen Wasser pro Tag von einem Hektar gem\u00e4\u00dfigtem Wald, das entspricht einer Wasserschicht von 3 bis 4 mm.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h2 class=\"wp-block-heading\">Bedeutung der Luftfeuchtigkeit (Hygrometrie)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einige Holzarten sind von Natur aus an atmosph\u00e4rische Bedingungen mit hoher Luftfeuchtigkeit angepasst. Dies gilt insbesondere f\u00fcr bestimmte amerikanische K\u00fcstenholzarten, bei denen die Nachfrage nach Bodenwasser mit steigender atmosph\u00e4rischer Luftfeuchtigkeit sinkt. Zu diesen Holzarten geh\u00f6ren die Hemlocktanne und die Riesen-Lebensbaum. Die Hygrometrie ist ein Faktor, der bei der Wahl der Holzarten (H\u00f6he, Topografie usw.) nicht zu vernachl\u00e4ssigen ist. Konsultieren Sie immer die Holzartenbl\u00e4tter des \u00d6kologischen Holzartenverzeichnisses (<a href=\"https:\/\/fichierecologique.be\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/fichierecologique.be<\/a>).<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-99e4dc9dca89f86fab903d244877a24a\">1.7. Beschr\u00e4nkungen der Bewurzelung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es sind die Wurzeln, die sich in einer Tiefe von mehr als einem Meter befinden, die in Trockenperioden f\u00fcr die Wasseraufnahme sorgen. Die untenstehenden Grafiken zeigen, dass sich 80 % der Wurzeln in einer Tiefe von bis zu 60 cm befinden, 12 % zwischen 60 cm und 1 m und nur 8 % in einer Tiefe von mehr als einem Meter (Studie an der Esche). Im Fr\u00fchjahr nimmt der Gro\u00dfteil der \u00aboberfl\u00e4chennahen\u00bb Wurzeln das f\u00fcr den Baum notwendige Wasser auf, doch im Laufe der Vegetationsperiode (weniger Wasser in geringer Tiefe verf\u00fcgbar) \u00fcbernehmen die tiefen Wurzeln diese Aufgabe und nehmen schlie\u00dflich fast das gesamte Wasser auf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daher ist die Bodenbeschaffenheit f\u00fcr das Wurzelwachstum von gr\u00f6\u00dfter Bedeutung und bestimmt zweifellos die Wahl der Arten, die auf einer bestimmten Station angepflanzt werden sollen (siehe nachfolgende Fotos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Haupteinschr\u00e4nkungen f\u00fcr die Wurzelbildung sind Staun\u00e4sse (Anaerobiose) und Bodenverdichtung. Die Empfindlichkeit gegen\u00fcber diesen beiden Faktoren ist je nach Baumart unterschiedlich. Zum Beispiel ist die Traubeneiche empfindlich gegen\u00fcber anhaltender Bodenvern\u00e4ssung, aber wenig empfindlich gegen\u00fcber Bodenverdichtung. Die Atlas-Zeder ist gegen\u00fcber beidem sehr empfindlich.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"376\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/quatre-graphique-1024x376.png\" alt=\"\" class=\"wp-image-38973\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/quatre-graphique-1024x376.png 1024w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/quatre-graphique-300x110.png 300w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/quatre-graphique-18x7.png 18w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/quatre-graphique-600x220.png 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Entwicklung der Wasserentnahme aus dem Boden im Laufe der Sommersaison in Abh\u00e4ngigkeit von der Tiefe (Esche). Nach Br\u00e9da N. et al. 2002.<\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"659\" height=\"951\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/gauche.png\" alt=\"\" class=\"wp-image-38974\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/gauche.png 659w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/gauche-208x300.png 208w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/gauche-8x12.png 8w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/gauche-600x866.png 600w\" sizes=\"auto, (max-width: 659px) 100vw, 659px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"659\" height=\"951\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/centre.png\" alt=\"\" class=\"wp-image-38975\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/centre.png 659w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/centre-208x300.png 208w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/centre-8x12.png 8w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/centre-600x866.png 600w\" sizes=\"auto, (max-width: 659px) 100vw, 659px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"659\" height=\"951\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/droite.png\" alt=\"\" class=\"wp-image-38976\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/droite.png 659w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/droite-208x300.png 208w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/droite-8x12.png 8w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/droite-600x866.png 600w\" sizes=\"auto, (max-width: 659px) 100vw, 659px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sch\u00f6ne Illustrationen der Korrelation zwischen D\u00fcrre-Anpassungsstrategie und Wurzelwachstumsbeschr\u00e4nkung. Links ein 12 Jahre alter Atlas-Zedernbaum (Toleranzstrategie durch Verz\u00f6gerung der Austrocknung) auf einem rissigen Felsboden. Nach einigen schwierigen Jahren haben die Wurzeln der Zeder ihren Weg in die Risse gefunden und sich tief ausgebreitet, um die Wasserversorgung zu sichern. In der Mitte ein gleichaltriger Atlas-Zedernbaum auf einem Boden mit einer Verdichtungsschicht in 40 cm Tiefe. Sein Wachstum ist praktisch null, die j\u00e4hrlichen Triebe vertrocknen. Entgegen der allgemeinen Annahme reguliert die Zeder ihre Evapotranspiration sehr schlecht und ist sehr schlecht trockenheitstolerant. Sie kompensiert dies durch tiefes Wurzelwachstum, vorausgesetzt, letzteres kann sich entwickeln. Rechts, 12 Jahre alte Arizona-Zypressen auf demselben Boden mit Verdichtungsschicht. Die Arizona-Zypresse wendet eine gemischte Strategie an. Wenn sie ihr Wurzelwachstum nicht entwickeln kann (Verz\u00f6gerungsstrategie), begrenzt sie ihre Evapotranspiration durch Schlie\u00dfen der Spalt\u00f6ffnungen (Vermeidungsstrategie). <em>Fotos: <a href=\"https:\/\/onf.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nationalforstamt<\/a><\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-6d728f724b5cbf2b311fe386cbaf63d0\">2. Bodenschutz<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-2b4ba3d72f3daca52bfa7e16602f653a\">2.1. N\u00e4hrstoffexport<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Je k\u00fcrzer die Umtriebszeit ist, desto h\u00f6her ist die N\u00e4hrstoffexportierung (Stickstoff, Phosphor, Kalium) aus dem Wald. Je h\u00f6her der Anteil an jungem Holz bei Holzerntema\u00dfnahmen ist, desto h\u00f6her ist die N\u00e4hrstoffexportierung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die nachstehende Grafik liefert wichtige Informationen zum Risiko der Bodenverarmung infolge der Waldbewirtschaftung. Der Gro\u00dfteil der N\u00e4hrstoffe (je nach Baumart 50 bis 80 %) befindet sich in \u00c4sten mit einem Durchmesser von weniger als 7 Zentimetern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daher ist es unbedingt zu vermeiden, die d\u00fcnnen \u00c4ste zu exportieren, insbesondere auf armen B\u00f6den, wo die Ganzbaumnutzung (einschlie\u00dflich der Krone) untersagt sein sollte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine der im Zuge des Klimawandels hervorgehobenen waldbaulichen Anpassungsma\u00dfnahmen ist die Verk\u00fcrzung der waldbaulichen Zyklen. Doch Vorsicht bei den Exporten: Verk\u00fcrzung der Umtriebszeiten ohne Begrenzung dieser wird verheerende Auswirkungen auf unsere Waldb\u00f6den haben, das wichtigste Produktionsmittel. Die Kumulation aus verk\u00fcrzten Umtriebszeiten und der Nutzung der gesamten Biomasse f\u00fchrt zu sehr starken Exporten, die die nat\u00fcrliche Mineralbilanz eines \u00d6kosystems nicht ausgleichen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein solcher Export laugt den Boden aus, der versauert. Dies wirkt sich negativ aus auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die strukturelle Stabilit\u00e4t: Der Boden wird anf\u00e4lliger f\u00fcr Erosion;<\/li>\n\n\n\n<li>die biologische Aktivit\u00e4t des Bodens;<\/li>\n\n\n\n<li>die Produktivit\u00e4t.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group has-border-color has-grey-color-border-color is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"border-width:3px;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Hinweis<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Schwadablage von Ernteresten ist nicht ratsam, da die N\u00e4hrstoffe lokal und nicht auf dem gesamten Feld zur\u00fcckgef\u00fchrt werden. Aus wirtschaftlichen Gr\u00fcnden wird diese Praxis jedoch dem Mulchen vorgezogen.<\/li>\n\n\n\n<li>Es ist leicht verst\u00e4ndlich, dass die Niederwaldwirtschaft die Art der waldbaulichen Behandlung ist, die die gr\u00f6\u00dften Auswirkungen auf den Holzexport hat, insbesondere bei kurzer Umtriebszeit. Fr\u00fchere Niederwaldmethoden haben viele Waldb\u00f6den ruiniert.<\/li>\n\n\n\n<li>Das auf dem Boden liegende Holz stellt eine nicht zu untersch\u00e4tzende, oft ignorierte Wasserreserve dar. Totes Holz speichert gro\u00dfe Mengen Wasser, die bei Trockenstress teilweise wieder an den Boden abgegeben werden.<\/li>\n\n\n\n<li>Die R\u00fcckf\u00fchrung von Holzasche in den Wald ist eine Scheinl\u00f6sung, da Holzasche keinen Stickstoff und keinen Kohlenstoff mehr enth\u00e4lt. Diese beiden Elemente sind jedoch f\u00fcr das Baumwachstum und die biologische Bodenaktivit\u00e4t von entscheidender Bedeutung.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-vert-claire-color-background-color has-background is-layout-constrained wp-container-core-group-is-layout-86409c69 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50);padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Laub- oder Nadelh\u00f6lzer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Angesichts des klimatischen Kontexts, auf B\u00f6den mit xerischem Charakter<sup>1<\/sup> Die Laubholzwirtschaft steht st\u00e4rker in der Kritik als die Nadelholzwirtschaft, da letztere eine gr\u00f6\u00dfere Bandbreite an Baumarten bietet, die trockenheitsresistent sind und gleichzeitig eine interessante Produktivit\u00e4t aufweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daher stehen Forstleute vor einem Paradoxon, da unsere Gesellschaft eher Laub- als Nadelb\u00e4ume bevorzugt und letztere sogar abwerten kann, manchmal werden sie f\u00fcr alle \u00dcbel verantwortlich gemacht. Es ist interessant festzustellen, dass in der Mittelmeerregion alle Forstbetriebe aus Nadelb\u00e4umen (Aleppo-Kiefer, See-Kiefer, Schirmkiefer usw.) bestehen.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vert-fonce-color-color has-alpha-channel-opacity has-vert-fonce-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Qualifiziert ein Milieu, das durch eine stark negative Wasserbilanz und daraus resultierende ausgepr\u00e4gte D\u00fcrre gekennzeichnet ist. Quelle: Forstwirtschaftsvokabular \u2013 \u00d6kologie, Verwaltung und Erhaltung von Waldgebieten, Christian Gauberville, Yves Bastien, CNPF-IDF \u2013 2011.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-9564b3cb074e183e334f431d37a959f7\">2.2. Bodenverdichtung vermeiden<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der F\u00f6rster muss wissen, dass:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Porosit\u00e4t des Bodens ist biologischen Ursprungs. Regenw\u00fcrmer bel\u00fcften insbesondere den Boden. Diese Bel\u00fcftung erm\u00f6glicht die Zirkulation von Wasser und Luft im Boden;<\/li>\n\n\n\n<li>Die Setzung ist \u00abendg\u00fcltig\u00bb (siehe Anmerkung), es gibt keine mechanische M\u00f6glichkeit zur Behebung;<\/li>\n\n\n\n<li>Die Setzung verringert die Produktivit\u00e4t.;<\/li>\n\n\n\n<li>Die wiederholte Durchfahrt von schweren Fahrzeugen auf B\u00f6den, selbst auf trockenen, f\u00fchrt zu einer Zerst\u00f6rung ihrer Struktur<sup>1<\/sup>\u2009;<\/li>\n\n\n\n<li>Best\u00e4nde auf verdichteten B\u00f6den werden bei Stress schneller geschw\u00e4cht, und die Ausf\u00e4lle sind folglich zahlreicher. Der Verlust der Porosit\u00e4t f\u00fchrt n\u00e4mlich zu zahlreichen Problemen wie Staun\u00e4sse, schlechter Durchwurzelung, verringerten Mykorrhizen, Verlust der biologischen Bodenaktivit\u00e4t...<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Daher sind einige Empfehlungen zwingend erforderlich, um die Durchfahrt von schweren Maschinen zu minimieren und einzugrenzen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>obligatorische Betriebsunterteilung und deren Einhaltung in den Leistungsbeschreibungen;<\/li>\n\n\n\n<li>die Holzverkabelung beg\u00fcnstigen (breitere Schotten);<\/li>\n\n\n\n<li>den Boden sparsam und punktuell bearbeiten (nur bei Vegetationsstillstand). Bodenkontakt vermeiden (z. B. Fr\u00e4sen), um eine Zerst\u00f6rung der Bodenstruktur (Bodenleben ist \u00fcberwiegend in den ersten 15\u201320 cm pr\u00e4sent) und eine Mineralisierung (Auswaschung in Gew\u00e4sser) zu verhindern;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group has-border-color has-grey-color-border-color is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"border-width:3px;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Hinweis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Oberfl\u00e4chenbodenbearbeitung wird die Wiederaufnahme der Pflanzen beg\u00fcnstigen, zum Beispiel mit einem Wender oder einer Scheibenegge. In der Tiefe bleibt die Verdichtung jedoch auch mit einer Tiefenlockerung bestehen. Sie h\u00e4lt l\u00e4nger an als das menschliche Zeitma\u00df. Bestimmte Arten k\u00f6nnen eine Erholung f\u00f6rdern, indem sie den Boden mit ihren Wurzeln aufbrechen. Die Zufuhr von organischem Material zur F\u00f6rderung der Bodenbiologie ist ein wesentlicher Bestandteil der Sanierung verdichteter B\u00f6den.<\/p>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Lamand\u00e9 M. et al., 2005. Auswirkungen der Forstwirtschaft auf die Bodenqualit\u00e4t. ONF \u2013 Collection dossiers forestiers Nr. 15, 131 S.<\/li>\n<\/ol>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-0abbe2d6f89553b83d162589e73a15f2\">3. Forstwirtschaftliche Strategie<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-21a5a4df72b0e740693d299362ec4cae\">3.1. Wie kann die Forstwirtschaft an den Klimawandel angepasst werden?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Neben der Einf\u00fchrung neuer Baumarten und Herk\u00fcnfte sowie der forstlichen Eingriffe, auf die wir im Folgenden eingehen, muss auch darauf geachtet werden, die Anpassungsf\u00e4higkeit der lokalen Ressource zur Geltung zu bringen und nicht anzunehmen, dass \u00abdie Sache verloren ist\u00bb. Die intrinsische Vielfalt ist bei B\u00e4umen, zumindest bei einigen Arten, sehr hoch, was ihnen gro\u00dfe Anpassungsf\u00e4higkeiten verleiht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um die W\u00e4lder an den Klimawandel anzupassen, muss der F\u00f6rster auf drei Ebenen handeln: Dichte, Struktur und Zusammensetzung. Dichte bezieht sich auf Auslichtungen, deren Intensit\u00e4t und H\u00e4ufigkeit. Die mehrschichtige Struktur bezieht sich auf einen gestuften Wald mit B\u00e4umen unterschiedlichen Alters (unregelm\u00e4\u00dfiger Hochwald). Schlie\u00dflich bezieht sich die Zusammensetzung auf das Mischungsverh\u00e4ltnis der Baumarten (Mischwald).<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-f68e4b0447382b108c07555acfaf7616\">Auf die Dichte einwirken<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ein dynamischeres Ausd\u00fcnnungsregime tendiert dazu, die Wasserbilanz zu verbessern, da einerseits weniger Regen durch das Laubwerk abgefangen wird, wodurch mehr Wasser den Boden erreicht, bevor es verdunstet, und andererseits der Wettbewerb um die Wasserressource geringer ist, da weniger B\u00e4ume vorhanden sind (geringere Evapotranspiration). Anders ausgedr\u00fcckt: Je dichter der Bestand ist, desto schneller wird der Schwellenwert f\u00fcr den Wasserdefizit des Bodens erreicht. Ausged\u00fcnnte Best\u00e4nde weisen w\u00e4hrend einer Trockenheit ein besseres Wachstum auf.<sup>1<\/sup> und eine bessere Widerstandsf\u00e4higkeit ihres Wachstums nach einer Trockenperiode.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allerdings st\u00f6\u00dft die Intensit\u00e4t der Eingriffe an ihre Grenzen, da Auslichtungen die verbleibenden B\u00e4ume beeintr\u00e4chtigen k\u00f6nnen. Denn je st\u00e4rker die Auslichtung, desto besser ist die Wasserbilanz des Bestandes, aber die Evapotranspiration auf Baumebene nimmt zu (Entwicklung der Baumkrone und im vollen Licht).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies ist eine wichtige Angabe, die man ber\u00fccksichtigen muss, insbesondere in der Mischwaldwirtschaft mit Dauerwald (SMCC). Die gezielt ausgew\u00e4hlten Zielb\u00e4ume werden st\u00e4rkerem Wasserstress ausgesetzt sein. In der SMCC ist es noch mehr als bei anderen forstwirtschaftlichen Behandlungen wichtig, eine optimale Anpassung der Baumarten an den Standort unter hydrologischen Gesichtspunkten sicherzustellen, insbesondere wenn Schattenbaumarten (z. B. Buche) ausgew\u00e4hlt werden, deren Bl\u00e4tter stark transpirieren. Man muss sich auch bewusst sein, dass das Licht, das den unteren Schichten zur Verf\u00fcgung gestellt wird, ihr Wachstum f\u00f6rdert, was sich nicht unerheblich auf die Wasserbilanz des gesamten Bestandes auswirkt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine dynamische Forstwirtschaft ist g\u00fcnstig f\u00fcr die Wasserversorgung des Bestands, vorausgesetzt, sie ist nicht:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>nicht \u00fcbertrieben;<\/li>\n\n\n\n<li>nicht brutal;<\/li>\n\n\n\n<li>und fr\u00fchzeitig (und das Auslichten nicht vernachl\u00e4ssigen).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die daraus resultierende Verk\u00fcrzung der Umdrehungen erm\u00f6glicht:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die Alterung von Best\u00e4nden zu begrenzen, die als Faktor f\u00fcr eine erh\u00f6hte Anf\u00e4lligkeit f\u00fcr alle Belastungen gilt;<\/li>\n\n\n\n<li>die Exposition gegen\u00fcber Risiken im Laufe der Zeit zu begrenzen;<\/li>\n\n\n\n<li>die Holzproduktion zugunsten der Minderung (Sequestrierung und Substitution) f\u00f6rdern.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dies unter der Bedingung, bei den Exporten wachsam zu bleiben (siehe Punkt 1 des vorherigen Kapitels).<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-b17bbb38f044b21f194f274c16266404\">Auf die Struktur einwirken<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">In Ebenen und auf B\u00f6den, die regelm\u00e4\u00dfig von D\u00fcrren betroffen sind, ist nicht erwiesen, dass der ungleichm\u00e4\u00dfige Hochwald eine der Waldbewirtschaftungsstrategien zur Begrenzung von Wasserstress ist. Es ist nicht m\u00f6glich auszusagen, dass ein System unter diesen Bedingungen besser ist als das andere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nat\u00fcrliche Best\u00e4nde, die regelm\u00e4\u00dfig D\u00fcrreperioden ausgesetzt sind, sind regelm\u00e4\u00dfig, zum Beispiel Aleppokiefernw\u00e4lder oder Ponderosa-Kiefernw\u00e4lder usw.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kann man daraus schlie\u00dfen, dass auf B\u00f6den mit x-lastiger Tendenz die unregelm\u00e4\u00dfige Struktur in Frage gestellt werden kann? Dieser Einwand stellt die unregelm\u00e4\u00dfige Plenterwirtschaft auf weniger anspruchsvollen und a fortiori optimalen Standorten keineswegs in Frage.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-3147a1fcd2dfe7217fb23c1882ce6ca5\">Auf die Zusammensetzung wirken<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Das Mischen von Essenzen weist positive und negative Wechselwirkungen auf.<br>Negative Interaktionen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Konkurrenz um die Ressource bei Arten derselben \u00f6kologischen Nische<sup>1<\/sup>\u2009;<\/li>\n\n\n\n<li>Der Antagonismus durch Alleopathie<sup>2<\/sup>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Positive Interaktionen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die Komplementarit\u00e4t: Die verf\u00fcgbaren Ressourcen werden besser zwischen Arten mit unterschiedlichen \u00f6kologischen Nischen geteilt (Ausl\u00e4ufer-\/Pfahlwurzeln, Schatten-\/Lichtbaumarten ...);<\/li>\n\n\n\n<li>die Fazilitation: n\u00fctzlicher Effekt einer Art auf eine andere Art, mit der sie interagiert.<br>Ein bekanntes Beispiel ist die Kombination von Robinie\/Pappel, die sich positiv auf die Pappel auswirkt, da diese durch die Stickstofffixierung der Robinie schneller w\u00e4chst. Ein weiteres Beispiel ist die Kombination von Erle\/Stieleiche auf tempor\u00e4rer Staun\u00e4sse. Die Erle treibt fr\u00fcher aus als die Stieleiche und trocknet den Boden aus (Evapotranspiration), wodurch die Eiche ihre Tiefenwurzelung leichter entwickeln kann, was sie widerstandsf\u00e4higer gegen sommerliche Trockenheit macht.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In der Praxis sind Wechselwirkungen aufgrund von Vielfalt positiv f\u00fcr das Ausma\u00df der Trockenheit (weniger ausgepr\u00e4gt) f\u00fcr Laubw\u00e4lder in gem\u00e4\u00dfigten Zonen auf tiefgr\u00fcndigem Boden.<sup>3<\/sup>. Die Aufteilung des unterirdischen Raums durch die Wurzeln scheint eine wichtige Rolle f\u00fcr die Auswirkung der Diversit\u00e4t auf die Trockenheitsresistenz zu spielen<sup>4<\/sup>.<\/p>\n\n\n\n<div class=\"wp-block-group has-border-color has-grey-color-border-color is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"border-width:3px;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Hinweis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unter mediterranen Bedingungen wird das Expositionsniveau gegen\u00fcber Trockenheit nicht durch die Vielfalt, sondern durch die St\u00e4ngeldichte gesteuert.<\/p>\n<\/div>\n\n\n\n<h5 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-6861f2023af6c7f29390774bb5ecf250\">Zusammensetzung und Wachstum<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Im Hinblick auf das Wachstum sind gemischte Best\u00e4nde in der Regel produktiver (insbesondere im Sinne von Mischungsertr\u00e4gen). Die untenstehenden Abbildungen geben uns folgende Informationen (linke Abbildung = Gesamteffekt der Mischung, rechte Abbildung = Effekt der Mischung nach Baumarten):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>In der Mischung Buche\/Eiche ist der Effekt f\u00fcr die Buche leicht positiv, die Eiche ist jedoch im Nachteil. Die Eiche wird in reinen Eichenbest\u00e4nden mehr Vitalit\u00e4t aufweisen als in Buchen\/Eichen-Best\u00e4nden.<\/li>\n\n\n\n<li>Die Mischung aus Buche und Fichte ist sehr g\u00fcnstig f\u00fcr das Wachstum der Buche, aber nicht f\u00fcr das der Fichte.;<\/li>\n\n\n\n<li>Die Mischung aus Buche und Wei\u00dftanne ist vor allem f\u00fcr das Wachstum der Buche g\u00fcnstig;<\/li>\n\n\n\n<li>Die Mischung aus Wei\u00dftanne und Fichte ist g\u00fcnstig f\u00fcr die Wei\u00dftanne;<\/li>\n\n\n\n<li>F\u00fcr die Mischung Eiche\/Kiefer ist der Mischungseffekt f\u00fcr die Eiche positiv, aber nicht f\u00fcr die Kiefer;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:75% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/graphiqe-peuplement-1024x543.png.webp\" alt=\"\" class=\"wp-image-38982 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:italic;font-weight:300\">Nach To\u00efgo M., et al. 2015. \u00dcberertragung in Mischw\u00e4ldern nimmt mit der Standortproduktivit\u00e4t ab. Journal of Ecology (103) S. 502-512<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Gesamtheit der Parameter, die die \u00f6kologischen Anforderungen oder die Lebensweise einer Art charakterisieren.<\/li>\n\n\n\n<li>Allelopathie ist ein biologisches Ph\u00e4nomen, bei dem ein Organismus eine oder mehrere biochemische Substanzen produziert, die die Keimung, das Wachstum, das \u00dcberleben und die Fortpflanzung anderer Organismen beeinflussen. Quelle: <a href=\"https:\/\/fr.wikipedia.org\/wiki\/All%C3%A9lopathie\" target=\"_blank\" rel=\"noreferrer noopener\">Wikipedia<\/a>.<\/li>\n\n\n\n<li>Grossiord C. et al., 2015. W\u00e4lder in gem\u00e4\u00dfigten Zonen und die Folgen des Klimawandels. RFF 2, S. 99-110.<\/li>\n\n\n\n<li>Grossiord C. et al., 2015. W\u00e4lder in gem\u00e4\u00dfigten Zonen und die Folgen des Klimawandels. RFF 2, S. 99-110.<\/li>\n<\/ol>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-9fd05a7441cc9197df41d536054ba48d\">4. Einf\u00fchrung neuer Baumarten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist n\u00fctzlich, daran zu erinnern, dass der europ\u00e4ische Kontinent aufgrund der Eiszeiten viele Arten verloren hat, was in Nordamerika nicht der Fall ist.<sup>1<\/sup>. So ist es unter vergleichbaren Breitengraden nicht ungew\u00f6hnlich, ein Verh\u00e4ltnis von zehn zu eins zugunsten des amerikanischen Kontinents in Bezug auf die Arten zu finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Einf\u00fchrung neuer Arten und Herk\u00fcnfte zielt darauf ab, eine Forstwirtschaft, insbesondere die Produktion, mit Baumarten aufrechtzuerhalten, die sich besser an trockenere und w\u00e4rmere Bedingungen anpassen.<sup>2<\/sup>. Sie st\u00fctzt sich auf die unterst\u00fctzte Wanderung (siehe unten) und die Einf\u00fchrung gebietsfremder Arten (siehe Kasten). Diese Einf\u00fchrungen erfordern ein tiefes Verst\u00e4ndnis der Aut\u00f6kologie<sup>3<\/sup> eszenzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt Trees For Future<sup>4<\/sup>, unter der Leitung der K\u00f6niglichen Forstlichen Gesellschaft Belgiens werden auf einem Netzwerk von Versuchsfl\u00e4chen im ganzen Land verschiedene Baumarten und -herk\u00fcnfte im Wald getestet (siehe Artikel auf Seite 8).<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-d647f7edb48376f203614ac9b98c967e\">Die assistierte Migration von Herk\u00fcnften<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei geht es darum, B\u00e4ume einer Art einzuf\u00fchren, die zwar bereits in diesem Gebiet vorkommt, jedoch aus dem s\u00fcdlichen Teil ihres Verbreitungsgebiets stammt. Von einer \u201eunterst\u00fctzten Migration von Herk\u00fcnften\u201c spricht man beispielsweise, wenn in Belgien eine Rotbuche gepflanzt wird, die aus einem in Italien oder S\u00fcdfrankreich geernteten Samen stammt. Das Ziel besteht dabei darin, die in diesen s\u00fcdlichen Populationen vorhandenen Gene f\u00fcr Trockenresistenz einzubringen und deren Verbreitung innerhalb der lokalen Populationen zu erm\u00f6glichen. Es geht also darum, die genetische Vielfalt einer lokalen Art zu bereichern, damit sie sich an das neue Klima anpassen kann. Die von dieser Art der Migration im Rahmen des Projekts Trees for Future betroffenen Baumarten sind die Traubeneiche, die Buche, die Winterlinde und in geringerem Ma\u00dfe die Flaumeiche, da diese zwar heimisch ist, bei uns heute jedoch sehr selten vorkommt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-rouge-color-color has-text-color has-link-color wp-elements-2d3ba625e5ecd2e3b09c828e51bf4e74\">Die assistierte Migration von Arten<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Fall wird eine Art eingef\u00fchrt, die noch nicht im Gebiet vorhanden ist, aber weiter s\u00fcdlich auf dem Kontinent unter klimatischen Bedingungen lebt, die denen \u00e4hneln, die in den kommenden Jahrzehnten in Belgien erwartet werden. Zum Beispiel spricht man von unterst\u00fctzter Artenwanderung, wenn mediterrane Eichen (Ungarische Eiche, Zotten-Eiche), mediterrane Tannen (Kretische Tanne, Bornm\u00fcller-Tanne) oder mediterrane Kiefern (Strandkiefer, Mazedonische Kiefer, Bosnische Kiefer) in Belgien gepflanzt werden.<\/p>\n\n\n\n<div class=\"wp-block-group has-orange-color-background-color has-background is-layout-constrained wp-container-core-group-is-layout-e3964afe wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h3 class=\"wp-block-heading\">Auf dem Weg zu einer kontinentalen Definition von Indigenit\u00e4t?<\/h3>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Gerahmter Auszug aus dem Artikel \u00abNeue Arten und Herk\u00fcnfte zur Anpassung an den Klimawandel einf\u00fchren: K\u00fchnheit oder Unbedachtheit?\u00bb von Nicolas Dassonville und Pascaline Leruth, Silva Belgica 1\/2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einheimische Baumarten haben durch ihre lange Existenz in einem bestimmten Gebiet eine Vielzahl von Interaktionen mit der lokalen Flora und Fauna aufgebaut. All diese Wechselwirkungen machen das \u00d6kosystem Wald so komplex und verleihen alten, sub-nat\u00fcrlichen W\u00e4ldern ihren biologischen Wert.<sup>1<\/sup>. Eine Baumart wird als einheimisch bezeichnet, wenn sie von Natur aus (ohne j\u00fcngste oder fr\u00fchere Eingriffe<sup>2<\/sup>, direkt oder indirekt vom Menschen) in einem bestimmten Gebiet vorkommt. Die Vorstellung von Indigenit\u00e4t h\u00e4ngt daher von der betrachteten geografischen Skala ab. Sollte eine in Rochefort nat\u00fcrlich vorkommende Art als einheimisch in der Famenne, in Wallonien, in Belgien, in Westeuropa gelten? Die Entscheidung ist relativ willk\u00fcrlich, kann aber die Forstpolitik, insbesondere in gesetzgeberischer Hinsicht, potenziell ma\u00dfgeblich beeinflussen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somit wird eine Art, die in Flandern heimisch ist (z. B. die Waldkiefer<sup>3<\/sup>) und daher in diesem gesamten Gebiet, einschlie\u00dflich Natura2000 und alten sub-nat\u00fcrlichen W\u00e4ldern, angepflanzt werden kann, kann in Wallonien als nicht-einheimisch betrachtet werden oder umgekehrt. Im Fall der Waldkiefer beispielsweise w\u00fcrde eine nationale Definition des Begriffs \"einheimisch\" die Situation sicherlich \u00e4ndern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Anbetracht der Tatsache, dass administrative Grenzen, sowohl nationale als auch regionale, nicht auf biologische Arten, einschlie\u00dflich B\u00e4ume, \u00fcbertragbar sind, und in Anbetracht des Klimawandels, der die Klimah\u00fcllen der Baumarten allm\u00e4hlich ver\u00e4ndert, w\u00e4re es nicht sinnvoller, die Eingeborenheit auf kontinentaler Ebene zu betrachten? Denn w\u00e4hrend der Eiszeiten und Zwischeneiszeiten ist es wahrscheinlich, dass die Baumarten miteinander in Kontakt gekommen sind. Man kann also davon ausgehen, dass die s\u00fcdeurop\u00e4ischen Baumarten eine Geschichte der Interaktion mit den Arten der lokalen Fauna und Flora haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sollte bei Einf\u00fchrungsstrategien f\u00fcr neue Arten eine Art wie die Ungarische Eiche nicht als heimisch in Europa betrachtet und daher nicht denselben Beschr\u00e4nkungen unterworfen werden wie eine Art asiatischen (z. B. Mandschurischer Eschenbaum) oder nordamerikanischen Ursprungs (z. B. K\u00fcstenmammutbaum), die keine historische Interaktion mit der lokalen Flora und Fauna aufweist und a priori ein geringeres biologisches Potenzial und ein h\u00f6heres invasives Risiko birgt?<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vert-fonce-color-color has-alpha-channel-opacity has-vert-fonce-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<ol class=\"wp-block-list\">\n<li>Subnat\u00fcrlich: bezeichnet eine Vegetation, die bestimmte Merkmale der Nat\u00fcrlichkeit aufweist, die jedoch - oft unvollst\u00e4ndig - die Spuren fr\u00fcherer anthropogener Aktivit\u00e4ten (Agropastoral, Materialabbau usw.) verdeckt. Quelle: Vocabulaire forestier. Ecology, management and conservation of green spaces, Christian Gauberville, Yves Bastien - CNPF-IDF - 2011.<\/li>\n\n\n\n<li>Ohne genaue Zeitangabe.<\/li>\n\n\n\n<li>Ob die Waldkiefer in Belgien heimisch ist, wird derzeit noch diskutiert. Angeblich wurde sie in Belgien erstmals 1675 in Kempen ausges\u00e4t. Quelle: \u00d6kologische Kartei der Baumarten.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center has-vert-claire-color-background-color has-background has-link-color wp-elements-e5f7821e75b34913e9d391087a1f8c0c\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60);padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60);grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"802\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited-1024x802.png\" alt=\"Trees for Future - Logo\" class=\"wp-image-35958 size-full\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited-1024x802.png 1024w, https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited-300x235.png 300w, https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited-15x12.png 15w, https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited-600x470.png 600w, https:\/\/srfb.be\/wp-content\/uploads\/2024\/03\/trees-for-future-logo-couleur-edited.png 1537w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Sie finden auf der Website <a href=\"https:\/\/climessences.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/climessences.fr\/<\/a> detaillierte Merkbl\u00e4tter zur Aut\u00f6kologie von 120 Baumarten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ziel dieser Merkbl\u00e4tter ist es, Akteuren der Forstwirtschaft Informationen \u00fcber autochthone und exotische Arten zur Verf\u00fcgung zu stellen, die f\u00fcr die franz\u00f6sische Forstwirtschaft von Interesse sein k\u00f6nnten.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-white-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.treesforfuture.be\/\" target=\"_blank\" rel=\"noreferrer noopener\">Besuchen Sie unsere Website Trees for Future<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:300\">\n<p class=\"wp-block-paragraph\">Artikel vom <a href=\"https:\/\/srfb.be\/de\/forstwirtschaftliche-informationen\/silva-belgica\/\">Silva Belgica<\/a> 4\/2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geschrieben von David Dancart<sup>1<\/sup>, nach dem Vortrag von Jean-Claude Tissaux<sup>2<\/sup> gegeben anl\u00e4sslich des Tages mit dem Titel \u00abAnpassungsstrategien der W\u00e4lder an den Klimawandel\u00bb, organisiert von der Royal Forest Society im Jahr 2022.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Verantwortlicher Silva Belgica, K\u00f6nigliche Forstgesellschaft Belgiens<\/li>\n\n\n\n<li>Jean-Claude Tissaux ist Projektmanager f\u00fcr die Wiederherstellung und Anpassung von W\u00e4ldern an den Klimawandel am Office National des For\u00eats (Frankreich). Er ist an zahlreichen Feldforschungsprojekten zu diesem Thema beteiligt.<\/li>\n<\/ol>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les changements climatiques impactent de nombreuses essences foresti\u00e8res et le fonctionnement m\u00eame des \u00e9cosyst\u00e8mes forestiers. Les forestiers s\u2019interrogent sur la meilleure mani\u00e8re d\u2019adapter leur for\u00eat afin de les rendre plus r\u00e9silientes. La chose n\u2019est pas ais\u00e9e car il n\u2019existe pas de recettes miracles et les facteurs \u00e0 prendre en compte \u00e9manent de domaines divers :&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>","protected":false},"author":18,"featured_media":38988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":791,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-38956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment adapter les for\u00eats aux changements climatiques? - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique<\/title>\n<meta name=\"description\" content=\"La r\u00e9silience foresti\u00e8re passe par une gestion int\u00e9gr\u00e9e\u00a0: choix d\u2019essences selon leur strat\u00e9gie face \u00e0 la s\u00e9cheresse, pr\u00e9servation des sols et techniques sylvicoles r\u00e9fl\u00e9chies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment adapter les for\u00eats aux changements climatiques? - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"og:description\" content=\"La r\u00e9silience foresti\u00e8re passe par une gestion int\u00e9gr\u00e9e\u00a0: choix d\u2019essences selon leur strat\u00e9gie face \u00e0 la s\u00e9cheresse, pr\u00e9servation des sols et techniques sylvicoles r\u00e9fl\u00e9chies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-03T12:08:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T12:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant-1010x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"C\u00e9dric Staes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/\"},\"author\":{\"name\":\"C\u00e9dric Staes\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/person\\\/dd159c756aa7647ee858e8da074f0c16\"},\"headline\":\"Comment adapter les for\u00eats aux changements climatiques?\",\"datePublished\":\"2025-09-03T12:08:09+00:00\",\"dateModified\":\"2025-09-03T12:17:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/\"},\"wordCount\":6681,\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/jeune-plant.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/\",\"name\":\"Comment adapter les for\u00eats aux changements climatiques? - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/jeune-plant.png\",\"datePublished\":\"2025-09-03T12:08:09+00:00\",\"dateModified\":\"2025-09-03T12:17:28+00:00\",\"description\":\"La r\u00e9silience foresti\u00e8re passe par une gestion int\u00e9gr\u00e9e\u00a0: choix d\u2019essences selon leur strat\u00e9gie face \u00e0 la s\u00e9cheresse, pr\u00e9servation des sols et techniques sylvicoles r\u00e9fl\u00e9chies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/jeune-plant.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/jeune-plant.png\",\"width\":1393,\"height\":1413,\"caption\":\"Jeune plant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/09\\\/03\\\/comment-adapter-les-forets-aux-changements-climatiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment adapter les for\u00eats aux changements climatiques?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/person\\\/dd159c756aa7647ee858e8da074f0c16\",\"name\":\"C\u00e9dric Staes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie kann man W\u00e4lder an den Klimawandel anpassen? - K\u00f6nigliche Forstwirtschaftliche Gesellschaft Belgiens","description":"Waldresilienz erfordert ein integriertes Management: Auswahl von Baumarten entsprechend ihrer Strategie im Umgang mit Trockenheit, Bodenschutz und durchdachte forstwirtschaftliche Techniken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/","og_locale":"de_DE","og_type":"article","og_title":"Comment adapter les for\u00eats aux changements climatiques? - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","og_description":"La r\u00e9silience foresti\u00e8re passe par une gestion int\u00e9gr\u00e9e\u00a0: choix d\u2019essences selon leur strat\u00e9gie face \u00e0 la s\u00e9cheresse, pr\u00e9servation des sols et techniques sylvicoles r\u00e9fl\u00e9chies.","og_url":"https:\/\/srfb.be\/de\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","article_published_time":"2025-09-03T12:08:09+00:00","article_modified_time":"2025-09-03T12:17:28+00:00","og_image":[{"width":1010,"height":1024,"url":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant-1010x1024.png","type":"image\/png"}],"author":"C\u00e9dric Staes","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#article","isPartOf":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/"},"author":{"name":"C\u00e9dric Staes","@id":"https:\/\/srfb.be\/#\/schema\/person\/dd159c756aa7647ee858e8da074f0c16"},"headline":"Comment adapter les for\u00eats aux changements climatiques?","datePublished":"2025-09-03T12:08:09+00:00","dateModified":"2025-09-03T12:17:28+00:00","mainEntityOfPage":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/"},"wordCount":6681,"publisher":{"@id":"https:\/\/srfb.be\/#organization"},"image":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#primaryimage"},"thumbnailUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant.png","articleSection":["Actualit\u00e9"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/","url":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/","name":"Wie kann man W\u00e4lder an den Klimawandel anpassen? - K\u00f6nigliche Forstwirtschaftliche Gesellschaft Belgiens","isPartOf":{"@id":"https:\/\/srfb.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#primaryimage"},"image":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#primaryimage"},"thumbnailUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant.png","datePublished":"2025-09-03T12:08:09+00:00","dateModified":"2025-09-03T12:17:28+00:00","description":"Waldresilienz erfordert ein integriertes Management: Auswahl von Baumarten entsprechend ihrer Strategie im Umgang mit Trockenheit, Bodenschutz und durchdachte forstwirtschaftliche Techniken.","breadcrumb":{"@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#primaryimage","url":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/09\/jeune-plant.png","width":1393,"height":1413,"caption":"Jeune plant"},{"@type":"BreadcrumbList","@id":"https:\/\/srfb.be\/2025\/09\/03\/comment-adapter-les-forets-aux-changements-climatiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/"},{"@type":"ListItem","position":2,"name":"Comment adapter les for\u00eats aux changements climatiques?"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/#website","url":"https:\/\/srfb.be\/","name":"K\u00f6nigliche Forstverein Belgiens","description":"Im Dienste des Waldes und der F\u00f6rster","publisher":{"@id":"https:\/\/srfb.be\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/srfb.be\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]},{"@type":"Person","@id":"https:\/\/srfb.be\/#\/schema\/person\/dd159c756aa7647ee858e8da074f0c16","name":"C\u00e9dric Staes"}]}},"_links":{"self":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts\/38956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/comments?post=38956"}],"version-history":[{"count":0,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts\/38956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/media\/38988"}],"wp:attachment":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/media?parent=38956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/categories?post=38956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/tags?post=38956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}