{"id":38896,"date":"2025-07-31T15:22:48","date_gmt":"2025-07-31T13:22:48","guid":{"rendered":"https:\/\/srfb.be\/?p=38896"},"modified":"2025-07-31T15:25:18","modified_gmt":"2025-07-31T13:25:18","slug":"waldtherapie-fuer-positive-psychische-gesundheit","status":"publish","type":"post","link":"https:\/\/srfb.be\/de\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/","title":{"rendered":"Waldbaden zur F\u00f6rderung positiver psychischer Gesundheit"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Das europ\u00e4ische Projekt Forest4Youth entstand aus der Zusammenarbeit zwischen dem Neuropsychiatrischen Zentrum Saint-Martin und der K\u00f6niglichen F\u00f6deration f\u00fcr Verteidigung der Natur (KFVN), um Jugendliche wieder mit der Natur zu verbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Initiative zielt darauf ab, hospitalisierten Jugendlichen ein immersives Walderlebnis zu bieten, als Antwort auf den wachsenden Bedarf an innovativen L\u00f6sungen im Bereich der psychischen Gesundheit. Das Projekt, bekannt f\u00fcr seinen innovativen Ansatz, wurde in einem speziellen Artikel auf Planet Health gew\u00fcrdigt, der die Bereicherung dieser Zusammenarbeit zwischen Pflegekr\u00e4ften und F\u00f6rstern zeigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finden Sie den Austausch der beiden Hauptbeteiligten unten:<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-47fc52ba wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-fb75d290 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center has-grey-color-background-color has-background wp-container-content-b04ba3db\" style=\"padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50);grid-template-columns:20% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"267\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Dr-Francois-Xavier-Polis.jpg\" alt=\"\" class=\"wp-image-38897 size-full\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Dr-Francois-Xavier-Polis.jpg 250w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Dr-Francois-Xavier-Polis-11x12.jpg 11w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Dr. Fran\u00e7ois Xavier Polis<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">leiter der Jugendstation L\u2019Athanor im CNP Saint-Martin<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center has-grey-color-background-color has-background wp-container-content-b04ba3db\" style=\"padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50);grid-template-columns:20% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"267\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Philippe-de-Wouters.jpg\" alt=\"\" class=\"wp-image-38898 size-full\" srcset=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Philippe-de-Wouters.jpg 250w, https:\/\/srfb.be\/wp-content\/uploads\/2025\/07\/Philippe-de-Wouters-11x12.jpg 11w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Philippe de Wouters<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Direktor des KFVN<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Wie ist dieses Projekt entstanden?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Fran\u00e7ois-Xavier Polis, Leiter der Jugendstation L\u2019Athanor im CNP Saint-Martin: \u201eDie Ausgangsfeststellung war, dass Jugendliche in unserer Station dazu neigten, sich in ihr Zimmer zur\u00fcckzuziehen, weshalb wir bef\u00fcrchteten, dass sich bei ihnen eine Art von Einschluss innerhalb der Station erneut entwickeln k\u00f6nnte. Daher wollten wir mehrere Ma\u00dfnahmen entwickeln, die diese jungen Menschen nach drau\u00dfen bringen w\u00fcrden. Diese Idee entstand aus meiner Begegnung mit Philippe de Wouters, Miteigent\u00fcmer eines wahrhaft zauberhaften Waldes im wallonischen Brabant, in dem eine ganz besondere Atmosph\u00e4re herrscht.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Philippe de Wouters, Direktor des KFVN: \u201eUnsere Erfahrung als F\u00f6rster besteht darin, in einem komplexen und lebendigen \u00d6kosystem zu arbeiten. Daher unser Wunsch, die Jugendlichen aus ihren vier W\u00e4nden herauszuholen und sie in ein lebendiges Umfeld zu integrieren, in dem jeder, ob jung oder alt, seinen Platz hat.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Haben diese Waldbaden-Therapien ihre Wirksamkeit bereits bewiesen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Polis: \u201eIch spreche lieber in Begriffen von Erfahrung als von Ergebnissen. Das Ziel ist nicht, dass die Jugendlichen als Versuchskaninchen dienen, um um jeden Preis die Effekte zu beobachten, sondern dass wir diesen Aufenthalt im Wald und die Losl\u00f6sung von Zeit und Bildschirmen nutzen, damit etwas geschieht \u2013 etwas im Sinne des Staunens.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Ma\u00dfnahmen sind in diesem 4-j\u00e4hrigen Projekt vorgesehen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ph. de Wouters: \u201eAus forstlicher Sicht geht es darum, verschiedene Aktivit\u00e4ten mit den Jugendlichen zu testen, um diejenigen zu identifizieren, die den gr\u00f6\u00dften Einfluss auf sie haben. Unser Ansatz der therapeutischen W\u00e4lder \u2013 die definierte gesundheitliche Vorteile bieten k\u00f6nnen \u2013 erstreckt sich auch auf st\u00e4dtische Gr\u00fcnfl\u00e4chen: Der Wald allein k\u00f6nnte die Menge der potenziellen Anfragen nicht bew\u00e4ltigen. Daher ist es in unserem Projekt essenziell, diese st\u00e4dtischen Gr\u00fcnfl\u00e4chen einzubeziehen, zumal die geplanten Aktivit\u00e4ten auch von kurzer Dauer sein k\u00f6nnen. Ebenso geh\u00f6rt Augmented Reality zum Projekt, um die Natur und ihre Wirkung auch f\u00fcr diejenigen zug\u00e4nglich zu machen, die sie nicht selbst erleben k\u00f6nnen, beispielsweise wenn sie hospitalisiert sind.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ist die Beteiligung der F\u00f6rster an diesem Projekt f\u00fcr die Pflegekr\u00e4fte wichtig?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Polis: \u201eIn Begleitung eines F\u00f6rsters \u00f6ffnet sich der Blick auf den Wald wirklich. Man sp\u00fcrt dieses Bed\u00fcrfnis nach Austausch und Weitergabe. Ohne die F\u00f6rster w\u00e4re unser Projekt leer. Gleichzeitig wollte ich auch unsere t\u00e4gliche Praxis nach zwei Jahren Erfahrung teilen. Au\u00dferdem freuen wir uns dank dieses europ\u00e4ischen Fonds darauf, andere Projektteams kennenzulernen, die unsere Praxis bereichern k\u00f6nnen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ph. de Wouters: \u201eUnser Wunsch ist es, dass der Wald nicht als Konsumobjekt betrachtet wird, sondern als ein lebendiges Ganzes, das mit den Jugendlichen verbunden ist. In Abstimmung mit den Therapeuten und dem F\u00f6rster, die an diesem Projekt beteiligt sind, m\u00f6chten wir au\u00dferdem, dass die Jugendlichen nach Hause gehen, nachdem sie etwas N\u00fctzliches und Gutes f\u00fcr den Wald getan haben. Denn damit der Wald uns guttut, muss er selbst gesund sein.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Daher die Bedeutung einer guten intersektoralen Zusammenarbeit?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ph. de Wouters: \u201eEs ist der Schnittpunkt von zwei Sektoren, die auf den ersten Blick nichts miteinander zu tun haben. Das gr\u00f6\u00dfte Ergebnis besteht darin, etwas Koh\u00e4rentes zwischen zwei Welten zu schaffen, indem gemeinsame Interessen herausgearbeitet werden, die sie festigen m\u00fcssen, um in Zukunft \u00e4hnliche Projekte aufzubauen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Polis: \u201eEs ist wichtig, deutlich zu machen, dass Psychiatrie nicht nur aus Medikation und Einsperrung besteht, sondern auch daraus, mit jungen Menschen in den Wald zu gehen \u2013 mit dem Ziel, dass dieses Pilotprojekt sich ein wenig \u00fcberall verbreiten kann.\u201c<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-grey-color-color has-alpha-channel-opacity has-grey-color-background-color has-background\"\/>\n\n\n\n<div class=\"wp-block-group has-small-font-size is-layout-constrained wp-container-core-group-is-layout-ee2332cf wp-block-group-is-layout-constrained\" style=\"font-style:italic;font-weight:400\">\n<p class=\"wp-block-paragraph\">Quellen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/fr.planet-health.be\/mind-body\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/fr.planet-health.be\/mind-body\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/<\/a><\/li>\n<\/ul>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le projet europ\u00e9en Forest4Youth est n\u00e9 de la collaboration entre le Centre Neuro Psychiatrique Saint-Martin et la Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique, pour reconnecter les adolescents \u00e0 la nature. Cette initiative vise \u00e0 offrir aux jeunes hospitalis\u00e9s une exp\u00e9rience immersive en for\u00eat, en r\u00e9ponse \u00e0 un besoin croissant de solutions innovantes en sant\u00e9 mentale. Reconnu&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/srfb.be\/de\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>","protected":false},"author":18,"featured_media":38672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":254,"footnotes":""},"categories":[7],"tags":[796],"class_list":["post-38896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-foret-et-sante-mentale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/srfb.be\/de\/2025\/07\/31\/waldtherapie-fuer-positive-psychische-gesundheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"og:description\" content=\"Le projet europ\u00e9en Forest4Youth est n\u00e9 de la collaboration entre le Centre Neuro Psychiatrique Saint-Martin et la Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique, pour reconnecter les adolescents \u00e0 la nature. Cette initiative vise \u00e0 offrir aux jeunes hospitalis\u00e9s une exp\u00e9rience immersive en for\u00eat, en r\u00e9ponse \u00e0 un besoin croissant de solutions innovantes en sant\u00e9 mentale. Reconnu... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/srfb.be\/de\/2025\/07\/31\/waldtherapie-fuer-positive-psychische-gesundheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T13:22:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T13:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1584\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9dric Staes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/\"},\"author\":{\"name\":\"C\u00e9dric Staes\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/person\\\/dd159c756aa7647ee858e8da074f0c16\"},\"headline\":\"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale\",\"datePublished\":\"2025-07-31T13:22:48+00:00\",\"dateModified\":\"2025-07-31T13:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/\"},\"wordCount\":825,\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/banner-forest4youth.jpeg\",\"keywords\":[\"for\u00eat et sant\u00e9 mentale\"],\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/\",\"name\":\"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/banner-forest4youth.jpeg\",\"datePublished\":\"2025-07-31T13:22:48+00:00\",\"dateModified\":\"2025-07-31T13:25:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/banner-forest4youth.jpeg\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/banner-forest4youth.jpeg\",\"width\":1584,\"height\":396,\"caption\":\"Forest4Youth\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/srfb.be\\\/2025\\\/07\\\/31\\\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/person\\\/dd159c756aa7647ee858e8da074f0c16\",\"name\":\"C\u00e9dric Staes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waldtherapie f\u00fcr positive psychische Gesundheitszust\u00e4nde - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/srfb.be\/de\/2025\/07\/31\/waldtherapie-fuer-positive-psychische-gesundheit\/","og_locale":"de_DE","og_type":"article","og_title":"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","og_description":"Le projet europ\u00e9en Forest4Youth est n\u00e9 de la collaboration entre le Centre Neuro Psychiatrique Saint-Martin et la Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique, pour reconnecter les adolescents \u00e0 la nature. Cette initiative vise \u00e0 offrir aux jeunes hospitalis\u00e9s une exp\u00e9rience immersive en for\u00eat, en r\u00e9ponse \u00e0 un besoin croissant de solutions innovantes en sant\u00e9 mentale. Reconnu... Read More","og_url":"https:\/\/srfb.be\/de\/2025\/07\/31\/waldtherapie-fuer-positive-psychische-gesundheit\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","article_published_time":"2025-07-31T13:22:48+00:00","article_modified_time":"2025-07-31T13:25:18+00:00","og_image":[{"width":1584,"height":396,"url":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg","type":"image\/jpeg"}],"author":"C\u00e9dric Staes","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#article","isPartOf":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/"},"author":{"name":"C\u00e9dric Staes","@id":"https:\/\/srfb.be\/#\/schema\/person\/dd159c756aa7647ee858e8da074f0c16"},"headline":"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale","datePublished":"2025-07-31T13:22:48+00:00","dateModified":"2025-07-31T13:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/"},"wordCount":825,"publisher":{"@id":"https:\/\/srfb.be\/#organization"},"image":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#primaryimage"},"thumbnailUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg","keywords":["for\u00eat et sant\u00e9 mentale"],"articleSection":["Actualit\u00e9"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/","url":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/","name":"Waldtherapie f\u00fcr positive psychische Gesundheitszust\u00e4nde - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","isPartOf":{"@id":"https:\/\/srfb.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#primaryimage"},"image":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#primaryimage"},"thumbnailUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg","datePublished":"2025-07-31T13:22:48+00:00","dateModified":"2025-07-31T13:25:18+00:00","breadcrumb":{"@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#primaryimage","url":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2025\/05\/banner-forest4youth.jpeg","width":1584,"height":396,"caption":"Forest4Youth"},{"@type":"BreadcrumbList","@id":"https:\/\/srfb.be\/2025\/07\/31\/la-therapie-forestiere-pour-des-etats-positifs-de-sante-mentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/"},{"@type":"ListItem","position":2,"name":"La th\u00e9rapie foresti\u00e8re pour des \u00e9tats positifs de sant\u00e9 mentale"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/#website","url":"https:\/\/srfb.be\/","name":"K\u00f6nigliche Forstverein Belgiens","description":"Im Dienste des Waldes und der F\u00f6rster","publisher":{"@id":"https:\/\/srfb.be\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/srfb.be\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]},{"@type":"Person","@id":"https:\/\/srfb.be\/#\/schema\/person\/dd159c756aa7647ee858e8da074f0c16","name":"C\u00e9dric Staes"}]}},"_links":{"self":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts\/38896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/comments?post=38896"}],"version-history":[{"count":0,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/posts\/38896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/media\/38672"}],"wp:attachment":[{"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/media?parent=38896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/categories?post=38896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/srfb.be\/de\/wp-json\/wp\/v2\/tags?post=38896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}